{"id":5579,"date":"2022-03-31T09:47:45","date_gmt":"2022-03-31T07:47:45","guid":{"rendered":"https:\/\/www.lyceelafayette.fr\/?p=5579"},"modified":"2022-03-31T09:47:47","modified_gmt":"2022-03-31T07:47:47","slug":"la-philharmonie-de-paris","status":"publish","type":"post","link":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/","title":{"rendered":"La Philharmonie de Paris"},"content":{"rendered":"\n<p>Ce mardi 29 mars, les \u00e9tudiants de 2 TSET et 2 SNIR se sont rendus \u00e0 la Philharmonie de Paris accompagn\u00e9s de quatre de leurs professeurs, dans le cadre de l\u2019\u00e9tude du th\u00e8me au programme de culture g\u00e9n\u00e9rale \u00ab\u00a0De la musique avant toute chose\u00a0\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-3-1024x768.png\" alt=\"\" class=\"wp-image-5596\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-3-1024x768.png 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-3-300x225.png 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-3-768x576.png 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-3-1536x1152.png 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-3-2048x1536.png 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-3-150x113.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Le matin, ils ont pu assister \u00e0 une r\u00e9p\u00e9tition g\u00e9n\u00e9rale d\u2019un concert donn\u00e9 le soir avec, au programme, une symphonie de Mahler et un concerto pour violon de Mozart interpr\u00e9t\u00e9 avec brio par un jeune violoniste virtuose.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"258\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-2-1024x258.png\" alt=\"\" class=\"wp-image-5580\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-2-1024x258.png 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-2-300x76.png 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-2-768x194.png 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-2-1536x387.png 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-2-2048x517.png 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/image-2-150x38.png 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>C\u2019\u00e9tait ainsi l\u2019occasion de voir des musiciens professionnels au travail.<\/p>\n\n\n\n<p>L\u2019apr\u00e8s-midi a \u00e9t\u00e9 consacr\u00e9 d\u2019une part \u00e0 la visite de l\u2019exposition temporaire d\u00e9di\u00e9e au hip-hop, et de l\u2019autre \u00e0 celle de la collection permanente de tous les magnifiques instruments de musique conserv\u00e9s par le mus\u00e9e. Toutes les deux ont laiss\u00e9 nos jeunes sur leur faim tant elles donnent envie de rester plus longtemps : un avant-go\u00fbt pour leur donner envie d\u2019y revenir !<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451-1024x768.jpg\" alt=\"\" data-id=\"5581\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5581\" class=\"wp-image-5581\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451-1024x768.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451-300x225.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451-768x576.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451-150x113.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-1024x683.jpg\" alt=\"\" data-id=\"5582\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5582\" class=\"wp-image-5582\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010872-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-1024x683.jpg\" alt=\"\" data-id=\"5583\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5583\" class=\"wp-image-5583\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010874-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-1024x683.jpg\" alt=\"\" data-id=\"5584\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5584\" class=\"wp-image-5584\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010876-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-1024x683.jpg\" alt=\"\" data-id=\"5585\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5585\" class=\"wp-image-5585\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010880-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-1024x683.jpg\" alt=\"\" data-id=\"5587\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5587\" class=\"wp-image-5587\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010886-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-1024x683.jpg\" alt=\"\" data-id=\"5588\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5588\" class=\"wp-image-5588\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010888-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-1024x683.jpg\" alt=\"\" data-id=\"5589\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5589\" class=\"wp-image-5589\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010890-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-1024x683.jpg\" alt=\"\" data-id=\"5590\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5590\" class=\"wp-image-5590\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010891-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-1024x683.jpg\" alt=\"\" data-id=\"5591\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5591\" class=\"wp-image-5591\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010897-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-1024x683.jpg\" alt=\"\" data-id=\"5592\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5592\" class=\"wp-image-5592\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010898-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-1024x683.jpg\" alt=\"\" data-id=\"5593\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5593\" class=\"wp-image-5593\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010899-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-1024x683.jpg\" alt=\"\" data-id=\"5594\" data-full-url=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-scaled.jpg\" data-link=\"https:\/\/www.lyceelafayette.fr\/?attachment_id=5594\" class=\"wp-image-5594\" srcset=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-1024x683.jpg 1024w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-300x200.jpg 300w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-768x512.jpg 768w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-1536x1024.jpg 1536w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-2048x1365.jpg 2048w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-150x100.jpg 150w, https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/P1010900-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce mardi 29 mars, les \u00e9tudiants de 2 TSET et 2 SNIR se sont rendus \u00e0 la Philharmonie de Paris accompagn\u00e9s de quatre de leurs professeurs, dans le cadre de l\u2019\u00e9tude du th\u00e8me au programme de culture g\u00e9n\u00e9rale \u00ab\u00a0De la musique avant toute chose\u00a0\u00bb. Le matin, ils ont pu assister&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/\">lire la suite<\/a><\/p>\n","protected":false},"author":8,"featured_media":5581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[108,15,109,33,107,72,44],"class_list":["post-5579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe","tag-108","tag-bts","tag-electrotechnique-2","tag-etudiants","tag-musique","tag-snir","tag-sortie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Philharmonie de Paris - Lyc\u00e9e La Fayette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Philharmonie de Paris - Lyc\u00e9e La Fayette\" \/>\n<meta property=\"og:description\" content=\"Ce mardi 29 mars, les \u00e9tudiants de 2 TSET et 2 SNIR se sont rendus \u00e0 la Philharmonie de Paris accompagn\u00e9s de quatre de leurs professeurs, dans le cadre de l\u2019\u00e9tude du th\u00e8me au programme de culture g\u00e9n\u00e9rale \u00ab\u00a0De la musique avant toute chose\u00a0\u00bb. Le matin, ils ont pu assister... lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyc\u00e9e La Fayette\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T07:47:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-31T07:47:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Facchin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Facchin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/\"},\"author\":{\"name\":\"Alexandre Facchin\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#\\\/schema\\\/person\\\/ce6db8a1157d50329e1fd65f9a9b5df8\"},\"headline\":\"La Philharmonie de Paris\",\"datePublished\":\"2022-03-31T07:47:45+00:00\",\"dateModified\":\"2022-03-31T07:47:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG_83451.jpg\",\"keywords\":[\"2022\",\"BTS\",\"Electrotechnique\",\"\u00e9tudiants\",\"musique\",\"SNIR\",\"sortie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/\",\"url\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/\",\"name\":\"La Philharmonie de Paris - Lyc\u00e9e La Fayette\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG_83451.jpg\",\"datePublished\":\"2022-03-31T07:47:45+00:00\",\"dateModified\":\"2022-03-31T07:47:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG_83451.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG_83451.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/2022\\\/03\\\/31\\\/la-philharmonie-de-paris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Philharmonie de Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/\",\"name\":\"Lyc\u00e9e La Fayette\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#organization\",\"name\":\"Lyc\u00e9e La Fayette\",\"url\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/llf_logo_alpha.png\",\"contentUrl\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/llf_logo_alpha.png\",\"width\":1583,\"height\":792,\"caption\":\"Lyc\u00e9e La Fayette\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC2AOQowoMGBKdY4ToZsf9mw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/#\\\/schema\\\/person\\\/ce6db8a1157d50329e1fd65f9a9b5df8\",\"name\":\"Alexandre Facchin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c94ab2db74f6be2880cb92feeab1c3c9a55baee6dab0b6f9fbb80e1bc3336b7a?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c94ab2db74f6be2880cb92feeab1c3c9a55baee6dab0b6f9fbb80e1bc3336b7a?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c94ab2db74f6be2880cb92feeab1c3c9a55baee6dab0b6f9fbb80e1bc3336b7a?s=96&d=blank&r=g\",\"caption\":\"Alexandre Facchin\"},\"url\":\"https:\\\/\\\/www.lyceelafayette.fr\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Philharmonie de Paris - Lyc\u00e9e La Fayette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/","og_locale":"fr_FR","og_type":"article","og_title":"La Philharmonie de Paris - Lyc\u00e9e La Fayette","og_description":"Ce mardi 29 mars, les \u00e9tudiants de 2 TSET et 2 SNIR se sont rendus \u00e0 la Philharmonie de Paris accompagn\u00e9s de quatre de leurs professeurs, dans le cadre de l\u2019\u00e9tude du th\u00e8me au programme de culture g\u00e9n\u00e9rale \u00ab\u00a0De la musique avant toute chose\u00a0\u00bb. Le matin, ils ont pu assister... lire la suite","og_url":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/","og_site_name":"Lyc\u00e9e La Fayette","article_published_time":"2022-03-31T07:47:45+00:00","article_modified_time":"2022-03-31T07:47:47+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451.jpg","type":"image\/jpeg"}],"author":"Alexandre Facchin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alexandre Facchin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/#article","isPartOf":{"@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/"},"author":{"name":"Alexandre Facchin","@id":"https:\/\/www.lyceelafayette.fr\/#\/schema\/person\/ce6db8a1157d50329e1fd65f9a9b5df8"},"headline":"La Philharmonie de Paris","datePublished":"2022-03-31T07:47:45+00:00","dateModified":"2022-03-31T07:47:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/"},"wordCount":173,"publisher":{"@id":"https:\/\/www.lyceelafayette.fr\/#organization"},"image":{"@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451.jpg","keywords":["2022","BTS","Electrotechnique","\u00e9tudiants","musique","SNIR","sortie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/","url":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/","name":"La Philharmonie de Paris - Lyc\u00e9e La Fayette","isPartOf":{"@id":"https:\/\/www.lyceelafayette.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/#primaryimage"},"image":{"@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451.jpg","datePublished":"2022-03-31T07:47:45+00:00","dateModified":"2022-03-31T07:47:47+00:00","breadcrumb":{"@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/#primaryimage","url":"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451.jpg","contentUrl":"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2022\/03\/IMG_83451.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.lyceelafayette.fr\/index.php\/2022\/03\/31\/la-philharmonie-de-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lyceelafayette.fr\/"},{"@type":"ListItem","position":2,"name":"La Philharmonie de Paris"}]},{"@type":"WebSite","@id":"https:\/\/www.lyceelafayette.fr\/#website","url":"https:\/\/www.lyceelafayette.fr\/","name":"Lyc\u00e9e La Fayette","description":"","publisher":{"@id":"https:\/\/www.lyceelafayette.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lyceelafayette.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lyceelafayette.fr\/#organization","name":"Lyc\u00e9e La Fayette","url":"https:\/\/www.lyceelafayette.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lyceelafayette.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2019\/06\/llf_logo_alpha.png","contentUrl":"https:\/\/www.lyceelafayette.fr\/wp-content\/uploads\/2019\/06\/llf_logo_alpha.png","width":1583,"height":792,"caption":"Lyc\u00e9e La Fayette"},"image":{"@id":"https:\/\/www.lyceelafayette.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UC2AOQowoMGBKdY4ToZsf9mw"]},{"@type":"Person","@id":"https:\/\/www.lyceelafayette.fr\/#\/schema\/person\/ce6db8a1157d50329e1fd65f9a9b5df8","name":"Alexandre Facchin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c94ab2db74f6be2880cb92feeab1c3c9a55baee6dab0b6f9fbb80e1bc3336b7a?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c94ab2db74f6be2880cb92feeab1c3c9a55baee6dab0b6f9fbb80e1bc3336b7a?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c94ab2db74f6be2880cb92feeab1c3c9a55baee6dab0b6f9fbb80e1bc3336b7a?s=96&d=blank&r=g","caption":"Alexandre Facchin"},"url":"https:\/\/www.lyceelafayette.fr\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/posts\/5579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5579"}],"version-history":[{"count":4,"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/posts\/5579\/revisions"}],"predecessor-version":[{"id":5598,"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/posts\/5579\/revisions\/5598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/media\/5581"}],"wp:attachment":[{"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lyceelafayette.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}